{"id":1074802,"date":"2025-08-16T00:00:00","date_gmt":"2025-08-15T23:00:00","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/aftersun-boat-party-playa-den-bossa-boat-parties-2025-08-16\/"},"modified":"2025-08-16T00:00:00","modified_gmt":"2025-08-15T23:00:00","slug":"aftersun-boat-party-playa-den-bossa-boat-parties-2025-08-16","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/es\/event\/aftersun-boat-party-playa-den-bossa-boat-parties-2025-08-16\/","title":{"rendered":"Aftersun Boat Party (Fiesta en barco Aftersun)"},"content":{"rendered":"<p>Aftersun es la nueva fiesta en barco m\u00e1s popular de Ibiza, y con raz\u00f3n  <\/p>\n<p>Prep\u00e1rate para unirte a 300 fiesteros con ideas afines en una fiesta en barco al atardecer con todo incluido para recordar, zarpando desde Playa d\u2019en Bossa hasta 6 veces por semana en 2025.  <\/p>\n<p>Es la fiesta que lo tiene todo: m\u00fasica incre\u00edble, barra libre con cerveza y sangr\u00eda, parada para nadar, la famosa puesta de sol de Ibiza y muy buen rollo por todas partes.<\/p>\n<p>Las entradas solo est\u00e1n disponibles online: \u00a1cons\u00edguelas antes de que se agoten!<\/p>\n<h4><span style=\"text-decoration: underline;\">Cartel:<\/span><\/h4>\n<p>DJs residentes<\/p>\n<p><strong>Compra tus entradas anticipadas para Aftersun Boat Party y ahorra dinero antes de ir a Ibiza.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DJs residentes<\/p>\n","protected":false},"template":"","wcs-type":[308,1537,2907],"dj":[],"class_list":["post-1074802","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-boat-party","wcs-type-aftersun-boat-party","wcs-type-2907","wcs-room-playa-den-bossa-boat-parties"],"acf":[],"_wcs_timestamp":"1755368100","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class\/1074802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media\/532900"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media?parent=1074802"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/wcs-type?post=1074802"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/dj?post=1074802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}