{"id":1058796,"date":"2026-01-13T13:39:23","date_gmt":"2026-01-13T13:39:23","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/kiss-pool-party-live-o-beach-2026-06-21\/"},"modified":"2026-03-25T18:25:21","modified_gmt":"2026-03-25T18:25:21","slug":"kiss-pool-party-live-o-beach-2026-06-21","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/es\/event\/kiss-pool-party-live-o-beach-2026-06-21\/","title":{"rendered":"KISS Pool Party Live"},"content":{"rendered":"<p>\u00danete a Kiss Pool Party Live para disfrutar de una tarde incre\u00edble en O Beach Ibiza.<\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Cartel<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/dj-cameo\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/cameo-150x150.jpg\" alt=\"DJ Cameo\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">DJ Cameo<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/sam-dungate\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/sun-dungate-150x150.jpg\" alt=\"Sam Dungate\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Sam Dungate<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cabezas de cartel: Por anunciar<br \/>\nDJ Cameo<br \/>\nSam Dungate<\/p>\n","protected":false},"template":"","wcs-type":[3958,4352,195,3816],"dj":[4595,4596],"class_list":["post-1058796","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-3958","wcs-type-kiss-pool-party-live","wcs-type-pool-party","wcs-type-sunday","wcs-room-o-beach","dj-sam-dungate","dj-dj-cameo"],"acf":[],"_wcs_timestamp":"1782046800","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class\/1058796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media\/993262"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media?parent=1058796"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/wcs-type?post=1058796"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/dj?post=1058796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}