{"id":1007153,"date":"2025-11-25T14:26:32","date_gmt":"2025-11-25T14:26:32","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/soul-heaven-o-beach-2026-08-01\/"},"modified":"2026-03-25T18:04:34","modified_gmt":"2026-03-25T18:04:34","slug":"soul-heaven-o-beach-2026-08-01","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/es\/event\/soul-heaven-o-beach-2026-08-01\/","title":{"rendered":"Soul Heaven"},"content":{"rendered":"<p>Desde 2013, Soul Heaven ha marcado el est\u00e1ndar para los s\u00e1bados en O Beach Ibiza: una fiesta en la piscina creada para los amantes de la m\u00fasica house exigentes que viven por el sol, el ritmo y la conexi\u00f3n. <\/p>\n<p>A\u00f1o tras a\u00f1o, contin\u00faa ofreciendo la mejor banda sonora vocal, llena de soul, funky disco y deep house.<\/p>\n<p>La residencia semanal de Soul Heaven siempre ha celebrado sus ra\u00edces con infusi\u00f3n de soul e inspiraci\u00f3n disco, construyendo un p\u00fablico fiel y dando la bienvenida a algunos de los artistas m\u00e1s respetados del mundo, incluidos Sandy Rivera (Kings of Tomorrow), Grant Nelson, Jamie 3:26, Kenny Dope, Mousse T, Purple Disco Machine, Dave Lee y Norman Jay, junto con talentos emergentes como Monki, Katie Goodman y Superlover.<\/p>\n<p>Espera actuaciones de alta energ\u00eda, una excelente banda sonora house y el inconfundible ambiente de O Beach Ibiza que hace de Soul Heaven una de las experiencias diurnas m\u00e1s solicitadas de la isla.<\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Cartel<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/jamie-love\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/jamie-love-150x150.jpg\" alt=\"Jamie Love\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Jamie Love<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/lucy-jane\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Lucy Jane\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Lucy Jane<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cabezas de cartel: por confirmar<br \/>\nJamie Love<br \/>\nLucy Jane<\/p>\n","protected":false},"template":"","wcs-type":[3815,3958,195,196],"dj":[4492,4560],"class_list":["post-1007153","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-saturday","wcs-type-3958","wcs-type-pool-party","wcs-type-soul-heaven","wcs-room-o-beach","dj-jamie-love","dj-lucy-jane"],"acf":[],"_wcs_timestamp":"1785589200","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class\/1007153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media\/993262"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media?parent=1007153"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/wcs-type?post=1007153"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/dj?post=1007153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}