{"id":1006629,"date":"2025-11-25T14:25:00","date_gmt":"2025-11-25T14:25:00","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/pool-party-o-beach-2026-06-19\/"},"modified":"2026-03-25T17:56:14","modified_gmt":"2026-03-25T17:56:14","slug":"pool-party-o-beach-2026-06-19","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/es\/event\/pool-party-o-beach-2026-06-19\/","title":{"rendered":"Pool Party"},"content":{"rendered":"<p>El viernes es una celebraci\u00f3n de la libertad. <\/p>\n<p>Seres extravagantes, \u00fanicos y de esp\u00edritu libre toman el control de la piscina en la fiesta m\u00e1s audaz de O Beach. Con house estimulante, artistas en vivo y un espectro completo de color y creatividad, la Pool Party es donde reina la autoexpresi\u00f3n.  <\/p>\n<p>Ven tal como eres. Todas las vibraciones son bienvenidas. O Beach no solo es fiesta.   TODOS JUEGAN \u2014 TODO EL D\u00cdA.<\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Cartel<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/dj-cameo\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/cameo-150x150.jpg\" alt=\"DJ Cameo\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">DJ Cameo<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/jamie-love\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/jamie-love-150x150.jpg\" alt=\"Jamie Love\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Jamie Love<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/lucy-jane\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Lucy Jane\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Lucy Jane<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/parris-taylor\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Parris Taylor\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Parris Taylor<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/sam-dungate\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/sun-dungate-150x150.jpg\" alt=\"Sam Dungate\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Sam Dungate<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/es\/dj\/albert-bace-percusion-en-directo\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Albert Bace (percusi\u00f3n en directo)\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Albert Bace (percusi\u00f3n en directo)<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>DJ Cameo<br \/>\nJamie Love<br \/>\nLucy Jane<br \/>\nParris Taylor<br \/>\nSam Dungate<br \/>\nAlbert Bace (percusi\u00f3n en directo)<\/p>\n","protected":false},"template":"","wcs-type":[195,3814,3958],"dj":[4495,4560,4595,4596,4597,4492],"class_list":["post-1006629","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-pool-party","wcs-type-friday","wcs-type-3958","wcs-room-o-beach","dj-parris-taylor","dj-lucy-jane","dj-sam-dungate","dj-dj-cameo","dj-albert-bace-percusion-en-directo","dj-jamie-love"],"acf":[],"_wcs_timestamp":"1781874000","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class\/1006629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media\/993262"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/media?parent=1006629"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/wcs-type?post=1006629"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/es\/wp-json\/wp\/v2\/dj?post=1006629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}