{"id":5032,"count":14,"description":"Cloonee ist ein aufstrebender Star der elektronischen Musikszene, bekannt f\u00fcr seine ansteckenden Beats und energiegeladenen Auftritte. Er stammt aus Gro\u00dfbritannien und hat sich bereits mit Tracks wie \"Be Good To Me\" und \"Lose Control\" einen Namen gemacht. Inspiriert von der Musik Ibizas bringt Cloonee eine einzigartige Mischung aus House und Techno auf die Tanzfl\u00e4che. Behalte diesen talentierten DJ im Auge, wenn er die Branche im Sturm erobert.   ","link":"https:\/\/ticketsibiza.com\/de\/dj\/cloonee\/","name":"Cloonee","slug":"cloonee","taxonomy":"dj","meta":[],"acf":{"dj_image":null,"featured_dj":false},"uncode_term_thumbnail_id":"585311","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/dj\/5032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/dj"}],"about":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/taxonomies\/dj"}],"wp:post_type":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class?dj=5032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}