{"id":1137322,"date":"2026-03-30T13:11:53","date_gmt":"2026-03-30T12:11:53","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/puro-reggaeton-es-paradis-2026-09-25\/"},"modified":"2026-03-30T13:11:53","modified_gmt":"2026-03-30T12:11:53","slug":"puro-reggaeton-es-paradis-2026-09-25","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/de\/event\/puro-reggaeton-es-paradis-2026-09-25\/","title":{"rendered":"Puro Reggaeton"},"content":{"rendered":"<p>Puro Reggaeton h\u00e4lt genau, was der Name verspricht \u2013 eine ganze Nacht voller Reggaeton, Latin Beats und Urban Music jeden Freitag im Es Paradis. Von Ende April bis Ende Oktober bedient es die wachsende Nachfrage nach Latin-inspirierten Clubn\u00e4chten auf der Insel. Die Party zieht ein junges, energiegeladenes Publikum an, das etwas anderes sucht als die typischen House- und Techno-Angebote anderswo auf Ibiza.  <\/p>\n<div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><div class=\"wcs-lineup__excerpt\"><p>Line-up wird noch bekannt gegeben<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Line-up wird noch bekannt gegeben<\/p>\n","protected":false},"template":"","wcs-type":[3958,3814,3957],"dj":[],"class_list":["post-1137322","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-3958","wcs-type-friday","wcs-type-puro-reggaeton","wcs-room-es-paradis"],"acf":[],"_wcs_timestamp":"1790373600","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class\/1137322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media\/1001671"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media?parent=1137322"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/wcs-type?post=1137322"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/dj?post=1137322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}