{"id":1136351,"date":"2026-03-30T13:06:21","date_gmt":"2026-03-30T12:06:21","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/you-know-the-vibes-es-paradis-2026-09-07\/"},"modified":"2026-03-30T13:06:21","modified_gmt":"2026-03-30T12:06:21","slug":"you-know-the-vibes-es-paradis-2026-09-07","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/de\/event\/you-know-the-vibes-es-paradis-2026-09-07\/","title":{"rendered":"Du kennst die Vibes"},"content":{"rendered":"<p>You Know The Vibes ist die Sonntags-Residency von Es Paradis und bringt einen Mix aus Urban, R&amp;B und kommerzieller Dance-Music in die ikonische Location in San Antonio. Die Party l\u00e4uft die ganze Saison von Ende April bis Ende Oktober und bietet eine verl\u00e4ssliche w\u00f6chentliche Option f\u00fcr alle, die sonntags beim Ausgehen einen eher mainstreamigen Soundtrack bevorzugen. Das Amphitheater-Setting von Es Paradis verleiht jeder Nacht dort ein besonderes Flair.  <\/p>\n<div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><div class=\"wcs-lineup__excerpt\"><p>Line-up wird noch bekannt gegeben<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Line-up wird noch bekannt gegeben<\/p>\n","protected":false},"template":"","wcs-type":[3958,10564,3810],"dj":[],"class_list":["post-1136351","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-3958","wcs-type-you-know-the-vibes","wcs-type-monday","wcs-room-es-paradis"],"acf":[],"_wcs_timestamp":"1788821100","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class\/1136351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media\/1001671"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media?parent=1136351"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/wcs-type?post=1136351"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/dj?post=1136351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}