{"id":1123856,"date":"2026-03-10T15:22:27","date_gmt":"2026-03-10T15:22:27","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/pantheon-cova-santa-2026-05-31\/"},"modified":"2026-03-10T15:22:27","modified_gmt":"2026-03-10T15:22:27","slug":"pantheon-cova-santa-2026-05-31","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/de\/event\/pantheon-cova-santa-2026-05-31\/","title":{"rendered":"PANTHE\u00d8N"},"content":{"rendered":"<p>Panthe\u00f8n kehrt f\u00fcr eine weitere volle Saison mit sonnt\u00e4glichen Sessions in die legend\u00e4re H\u00f6hlen-Location Cova Santa zur\u00fcck. Die Party hat sich als eines der best\u00e4ndigsten w\u00f6chentlichen Events auf der Insel etabliert und zieht ein Publikum an, das tiefere, anspruchsvollere Sounds in einer Umgebung sch\u00e4tzt, die jeden Beat verst\u00e4rkt. Die nat\u00fcrliche Akustik des H\u00f6hlensystems von Cova Santa verleiht der Musik eine Resonanz, die man so nirgendwo anders replizieren kann.  <\/p>\n<div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><div class=\"wcs-lineup__excerpt\"><p>Line-up wird noch bekannt gegeben<\/p>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Line-up wird noch bekannt gegeben<\/p>\n","protected":false},"template":"","wcs-type":[3958,3570,3816],"dj":[],"class_list":["post-1123856","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-3958","wcs-type-pantheon","wcs-type-sunday","wcs-room-cova-santa"],"acf":[],"_wcs_timestamp":"1780250400","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class\/1123856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media\/1132772"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media?parent=1123856"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/wcs-type?post=1123856"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/dj?post=1123856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}