{"id":1109009,"date":"2026-02-05T16:21:21","date_gmt":"2026-02-05T16:21:21","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/nothing-new-pool-party-ibiza-rocks-2026-07-06\/"},"modified":"2026-02-05T16:21:21","modified_gmt":"2026-02-05T16:21:21","slug":"nothing-new-pool-party-ibiza-rocks-2026-07-06","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/de\/event\/nothing-new-pool-party-ibiza-rocks-2026-07-06\/","title":{"rendered":"Nothing New Pool Party"},"content":{"rendered":"<p>Brandneu f\u00fcr 2026 bringt Nothing New jeden Montag im neu gestalteten Ibiza Rocks Pool Club die Nostalgie zur\u00fcck. Vom 27. April bis zum 28. September kannst du deine Woche mit einem Soundtrack, der ausschlie\u00dflich aus Hymnen von vor 2016 besteht, zur\u00fcckspulen. Erwarte Throwback-Dance, R&amp;B, Rap, Indie und alles dazwischen \u2013 wenn es nicht mindestens 10 Jahre alt ist, wird es nicht gespielt. Texte, die du kennst, Vibes, die du liebst, und eine Menge, die zum Singen gekommen ist. Raus mit dem Neuen, rein mit dem Unvergesslichen.    <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/ibiza-rocks\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Ibiza Rocks\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Ibiza Rocks<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ibiza Rocks Resident DJs<\/p>\n","protected":false},"template":"","wcs-type":[3958,8358,195,3810],"dj":[8374],"class_list":["post-1109009","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-3958","wcs-type-nothing-new-pool-party","wcs-type-pool-party","wcs-type-monday","wcs-room-ibiza-rocks","dj-ibiza-rocks"],"acf":[],"_wcs_timestamp":"1783353600","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class\/1109009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media\/1107165"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media?parent=1109009"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/wcs-type?post=1109009"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/dj?post=1109009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}