{"id":1099635,"date":"2026-02-03T11:28:57","date_gmt":"2026-02-03T11:28:57","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/ibiza-boat-club-playa-den-bossa-boat-parties-2026-08-16\/"},"modified":"2026-02-05T09:55:26","modified_gmt":"2026-02-05T09:55:26","slug":"ibiza-boat-club-playa-den-bossa-boat-parties-2026-08-16","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/de\/event\/ibiza-boat-club-playa-den-bossa-boat-parties-2026-08-16\/","title":{"rendered":"Ibiza Boat Club"},"content":{"rendered":"<p>Du kannst jetzt aufh\u00f6ren zu suchen: Das ist die Ibiza Bootsparty, auf die du f\u00fcr 2026 gewartet hast.<\/p>\n<p>Die Ibiza Boat Club Five Star Bootsparty hat alles zu bieten: Es ist ein VIP-Erlebnis f\u00fcr alle G\u00e4ste an Bord. Wie k\u00f6nnen wir sie beschreiben?  Nun, du wirst dich f\u00fchlen, als w\u00e4rst du in deinem eigenen Beach Club auf See. <\/p>\n<p>Die Getr\u00e4nke flie\u00dfen, die Beats pumpen auf ihrem VOID Soundsystem und du bist mit weiteren 100 G\u00e4sten zusammen, die w\u00e4hrend der 3-st\u00fcndigen Fahrt die H\u00e4nde in die Luft werfen.<\/p>\n<p>W\u00e4hle aus unbegrenzten Bieren, Sangria und Cava, w\u00e4hrend du Ibizas wundersch\u00f6ne K\u00fcste genie\u00dft.<\/p>\n<p>Es gibt auch Essen, in das man sich vertiefen kann: Paella, irgendjemand? Und du hast die M\u00f6glichkeit, ins Meer zu springen und mit dem Wasserspielzeug zu spielen. <\/p>\n<p>Der Ibiza Boat Club sticht an mehreren Tagen jede Woche der Saison von Playa d\u2019en Bossa aus in See. <\/p>\n<p>Wie du siehst, sind wir gro\u00dfe Fans. Es ist nicht umsonst unsere am meisten empfohlene Ibiza Bootsparty.  Sie hat in der letzten Saison auch den Tripadvisor Traveler Choice Award erhalten.<br \/>\nWorauf wartest du noch? Wir sehen uns an Bord!<\/p>\n<h4><div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><div class=\"wcs-lineup__excerpt\"><p>Resident DJs<\/p>\n<\/div><\/div><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Resident DJs<\/p>\n","protected":false},"template":"","wcs-type":[308,1453,3816,3958],"dj":[],"class_list":["post-1099635","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-boat-party","wcs-type-ibiza-boat-club","wcs-type-sunday","wcs-type-3958","wcs-room-playa-den-bossa-boat-parties"],"acf":[],"_wcs_timestamp":"1786885200","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class\/1099635","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media\/994338"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media?parent=1099635"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/wcs-type?post=1099635"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/dj?post=1099635"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}