{"id":1097637,"date":"2026-02-03T11:39:30","date_gmt":"2026-02-03T11:39:30","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/aftersun-boat-party-playa-den-bossa-boat-parties-2026-06-10\/"},"modified":"2026-02-05T10:07:52","modified_gmt":"2026-02-05T10:07:52","slug":"aftersun-boat-party-playa-den-bossa-boat-parties-2026-06-10","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/de\/event\/aftersun-boat-party-playa-den-bossa-boat-parties-2026-06-10\/","title":{"rendered":"Aftersun Boat Party"},"content":{"rendered":"<p>Aftersun ist zur\u00fcck f\u00fcr 2026 \u2013 und immer noch die angesagteste neue Ibiza Bootsparty <\/p>\n<p>Feier mit 300+ Partybegeisterten auf einer unvergesslichen All-inclusive-Sunset-Cruise, die bis zu sechsmal pro Woche den ganzen Sommer \u00fcber von Playa d\u2019en Bossa aus in See sticht.<\/p>\n<p>Erwarte Non-Stop-Vibes mit unglaublicher Musik, einer Open Bar mit Bier &amp; Sangria, einem erfrischenden Badestopp und Logenpl\u00e4tzen f\u00fcr Ibizas legend\u00e4ren Sonnenuntergang \u2013 und das alles mit einer begeisterten Menge und unschlagbarer Energie.<\/p>\n<p>Tickets sind nur online erh\u00e4ltlich \u2013 sichere dir jetzt deine, bevor sie weg sind!<\/p>\n<h4><div class=\"wcs-lineup wcs-lineup--text\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><div class=\"wcs-lineup__excerpt\"><p>Resident DJs<\/p>\n<\/div><\/div><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Resident DJs<\/p>\n","protected":false},"template":"","wcs-type":[3812,3958,308,1537],"dj":[],"class_list":["post-1097637","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-wednesday","wcs-type-3958","wcs-type-boat-party","wcs-type-aftersun-boat-party","wcs-room-playa-den-bossa-boat-parties"],"acf":[],"_wcs_timestamp":"1781115300","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class\/1097637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media\/994343"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media?parent=1097637"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/wcs-type?post=1097637"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/dj?post=1097637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}