{"id":1093075,"date":"2026-02-02T21:04:16","date_gmt":"2026-02-02T21:04:16","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/ibiza-rocks-pool-party-ibiza-rocks-2026-06-30\/"},"modified":"2026-02-04T15:54:49","modified_gmt":"2026-02-04T15:54:49","slug":"ibiza-rocks-pool-party-ibiza-rocks-2026-06-30","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/de\/event\/ibiza-rocks-pool-party-ibiza-rocks-2026-06-30\/","title":{"rendered":"Ibiza Rocks Pool Party"},"content":{"rendered":"<p>Die originale Poolside-Session, die von Tag zu Nacht geht, ist zur\u00fcck und lauter denn je. Jeden Dienstag im Ibiza Rocks bringt die Ibiza Rocks Pool Party die Energie mit Non-Stop-Bangern, Live-MCs, T\u00e4nzern, aufblasbaren Gegenst\u00e4nden und einer unschlagbaren Menge. Erwarte riesige Hymnen, schonungslose Vibes und Hauptdarsteller-Momente auf der legend\u00e4rsten Tanzfl\u00e4che der Insel &#8211; dem Pool. Schnapp dir deine Crew, tauche ein und lass das Chaos beginnen.   <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/ibiza-rocks-djs\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Ibiza Rocks DJs\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Ibiza Rocks DJs<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ibiza Rocks DJs<\/p>\n","protected":false},"template":"","wcs-type":[2463,3811,3958,195],"dj":[8318],"class_list":["post-1093075","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-ibiza-rocks-pool-party","wcs-type-tuesday","wcs-type-3958","wcs-type-pool-party","wcs-room-ibiza-rocks","dj-ibiza-rocks-djs"],"acf":[],"_wcs_timestamp":"1782835200","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class\/1093075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media\/1107165"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media?parent=1093075"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/wcs-type?post=1093075"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/dj?post=1093075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}