{"id":1091528,"date":"2026-01-30T15:37:49","date_gmt":"2026-01-30T15:37:49","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/our-house-hi-ibiza-2026-07-15\/"},"modified":"2026-06-26T11:31:24","modified_gmt":"2026-06-26T10:31:24","slug":"our-house-hi-ibiza-2026-07-15","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/de\/event\/our-house-hi-ibiza-2026-07-15\/","title":{"rendered":"Our House"},"content":{"rendered":"<p>Die Chartst\u00fcrmer MEDUZA und James Hype kehren f\u00fcr eine weitere explosive Saison von Our House nach H\u00ef Ibiza zur\u00fcck und \u00fcbernehmen die Mittwochabende vom 27. Mai bis zum 30. September.<\/p>\n<p>Our House verbindet Stadion-Energie mit Clubkultur und ist ein hochoktaniges Erlebnis, bei dem genre\u00fcbergreifende Sets, Big-Room-Hymnen und Next-Level-Produktion aufeinandertreffen. Erwarte Back-to-Back-Wahnsinn, \u00dcberraschungsg\u00e4ste und eine Tanzfl\u00e4che voller purer Elektrizit\u00e4t. Ein Highlight der Ibiza-Saison 2026.  <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/james-hype\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/james-hype-150x150.jpg\" alt=\"James Hype\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">James Hype<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/meduza\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/meduza-150x150.jpg\" alt=\"Meduza\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Meduza<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/layla-benitez\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Layla Benitez\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Layla Benitez<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/lanna\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Lanna\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Lanna<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/zamna-sound-system\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Zamna Sound System\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Zamna Sound System<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/g-pol\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"G - Pol\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">G - Pol<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/silvio-soul\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Silvio Soul\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Silvio Soul<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>James Hype<br \/>\nMeduza\u00b3<br \/>\nLayla Benitez<br \/>\nLanna<br \/>\nClub Room &#8211; Offweek<br \/>\nZamna Sound System<br \/>\nG &#8211; Pol<br \/>\nSilvio Soul<\/p>\n","protected":false},"template":"","wcs-type":[307,2237,3812,3958],"dj":[5238,12120,13022,14797,14854,14855,5237],"class_list":["post-1091528","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-superclub","wcs-type-our-house","wcs-type-wednesday","wcs-type-3958","wcs-room-hi-ibiza","dj-meduza","dj-layla-benitez","dj-lanna","dj-zamna-sound-system","dj-g-pol","dj-silvio-soul","dj-james-hype"],"acf":[],"_wcs_timestamp":"1784156340","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class\/1091528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media\/1083044"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media?parent=1091528"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/wcs-type?post=1091528"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/dj?post=1091528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}