{"id":1085831,"date":"2025-09-02T00:00:00","date_gmt":"2025-09-01T23:00:00","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/outset-ibiza-closing-party-eden-2025-09-02\/"},"modified":"2025-09-02T00:00:00","modified_gmt":"2025-09-01T23:00:00","slug":"outset-ibiza-closing-party-eden-2025-09-02","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/de\/event\/outset-ibiza-closing-party-eden-2025-09-02\/","title":{"rendered":"Outset Ibiza Closing-Party \/ Abschlussparty"},"content":{"rendered":"<p>Tanze hart mit Reboot im Eden Ibiza. Das irische Outfit kehrt nach zwei \u00fcberaus erfolgreichen Saisons im Eden, dem ber\u00fchmten San Antonio Superclub, zur\u00fcck. <\/p>\n<p>Erlebe Reboot DJs &amp; G\u00e4ste jeden Dienstag im Jahr 2024 im ber\u00fchmten San Antonio Club.<\/p>\n<h4><span style=\"text-decoration: underline;\">Line-up<\/span><\/h4>\n<p>Black Traffic<br \/>\nblk.<br \/>\nM_UNKNOWN_D<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Black Traffic<br \/>\nblk.<br \/>\nM_UNKNOWN_D<\/p>\n","protected":false},"template":"","wcs-type":[2907,3811,307,309,1696],"dj":[7339,7340,7341],"class_list":["post-1085831","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-2907","wcs-type-tuesday","wcs-type-superclub","wcs-type-closing-party","wcs-type-outset-ibiza","wcs-room-eden","dj-blk","dj-black-traffic","dj-m_unknown_d"],"acf":[],"_wcs_timestamp":"1756853940","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class\/1085831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media\/330372"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media?parent=1085831"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/wcs-type?post=1085831"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/dj?post=1085831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}