{"id":1077261,"date":"2025-09-03T00:00:00","date_gmt":"2025-09-02T23:00:00","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/formentera-wonders-boat-trip-playa-den-bossa-boat-parties-2025-09-03\/"},"modified":"2025-09-03T00:00:00","modified_gmt":"2025-09-02T23:00:00","slug":"formentera-wonders-boat-trip-playa-den-bossa-boat-parties-2025-09-03","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/de\/event\/formentera-wonders-boat-trip-playa-den-bossa-boat-parties-2025-09-03\/","title":{"rendered":"Formentera Wonders Bootsfahrt"},"content":{"rendered":"<p>Setze die Segel f\u00fcr einen Tag voller Entdeckungen mit Formentera Wonders \u2013 On the Sea Adventure, einem 5-st\u00fcndigen Katamaran-Ausflug von Ibiza zu den atemberaubenden Ufern von Ses Illetes und Cala Saona. Mit einer Open Bar, Wassersportarten und frisch zubereiteter Paella ist dies die perfekte Mischung aus Abenteuer und Entspannung. <\/p>\n<p>\u2e3b<\/p>\n<p>Reiseplan\u00fcbersicht<\/p>\n<p>Check-in: 8:45 Uhr<br \/>\nTreffen Sie sich vor der Happiness Bar in Playa d\u2019en Bossa, wo Sie von unserer freundlichen Hostess eingecheckt werden, Geschenke erhalten und alle Fragen vor dem Einsteigen beantwortet werden.<\/p>\n<p>Beginnen Sie Ihre Reise:<br \/>\nGehen Sie an Bord und lassen Sie sich von einem mehrsprachigen Reiseleiter (Spanisch, Englisch, Italienisch) begr\u00fc\u00dfen. Genie\u00dfen Sie anschlie\u00dfend ein Fr\u00fchst\u00fccksbuffet und eine offene Bar, w\u00e4hrend wir zu den kristallklaren Gew\u00e4ssern von Formentera segeln.<\/p>\n<p>\u2e3b<\/p>\n<p>Stopps &amp; Highlights<\/p>\n<p> Ses Illetes<br \/>\nDas erste Ziel ist das weltber\u00fchmte Ses Illetes, das zum besten Strand Spaniens und zu einem der bestbewerteten K\u00fcsten Europas gew\u00e4hlt wurde. Hier genie\u00dfen Sie live zubereitete Paella am Meer und k\u00f6nnen an einer Vielzahl von Wasseraktivit\u00e4ten teilnehmen, darunter:<br \/>\n \u2022 Paddle-Boarding<br \/>\n \u2022 Schnorcheln<br \/>\n \u2022 Sea Scooter Fahrten<br \/>\n \u2022 Wasserrutsche und Trampolin-Spa\u00df <\/p>\n<p> Cala Saona<br \/>\nAls n\u00e4chstes ankern Sie in Cala Saona, einer friedlichen Bucht, die von roten Klippen und kristallklarem Wasser umgeben ist. Bekannt als das Juwel der Westk\u00fcste Formenteras, ist es der perfekte Ort, um die Ruhe zu genie\u00dfen. <\/p>\n<p>\u2e3b<\/p>\n<p>R\u00fcckkehr nach Ibiza<\/p>\n<p>Gegen 13:00 Uhr f\u00e4hrt das Boot zur\u00fcck, sodass Sie Zeit haben, sich zu entspannen, zu plaudern und die Aussicht mit einem entspannten Soundtrack im Hintergrund zu genie\u00dfen. Sie kommen gegen 14:00 Uhr wieder in Playa d\u2019en Bossa an und beenden damit einen magischen Halbtagesausflug. <\/p>\n<p>\u2e3b<\/p>\n<p>Was ist inbegriffen<\/p>\n<p>\u2714 5-st\u00fcndiger Katamaran-Ausflug nach Formentera<br \/>\n\u2714 Open Bar: Bier, Sangria, Softdrinks und S\u00e4fte<br \/>\n\u2714 Fr\u00fchst\u00fccksbuffet und frisch zubereitete Paella<br \/>\n\u2714 Wasseraktivit\u00e4ten: Schnorcheln, Paddle-Boarding, Sea Scooter, Rutsche und Trampolin<br \/>\n\u2714 Mehrsprachiger Reiseleiter (Spanisch, Englisch, Italienisch)<br \/>\n\u2714 Lounge-Musik w\u00e4hrend der gesamten Reise<br \/>\n\u2714 Geschenke beim Check-in<\/p>\n<p>\u2e3b<\/p>\n<p>Begleite Formentera Wonders auf einem halbt\u00e4gigen Abenteuer, bei dem Meer, Sonne und Landschaft zusammenkommen, um unvergessliche Erinnerungen zu schaffen.<\/p>\n<p>Wichtige Infos:<\/p>\n<p>Das Formentera Wonders \u2013 On The Sea Adventure-Erlebnis wurde speziell f\u00fcr Reisende entwickelt, die Segeln, das Meer und Wasseraktivit\u00e4ten rund um das Boot genie\u00dfen.<\/p>\n<p> Dieser Ausflug beinhaltet keine Ausschiffung auf der Insel Formentera, und es ist nicht gestattet, Paddle-Surf-Ausr\u00fcstung zu benutzen, um den Strand zu erreichen.<\/p>\n<p>Dies ist ein perfektes Erlebnis, um auf dem Wasser zu bleiben: schwimmen, schnorcheln, Paddle-Surfen auf offener See genie\u00dfen, von der Wasserrutsche des Bootes direkt ins Meer rutschen, den Meeresboden entdecken und an Bord entspannen.<\/p>\n<p>Ankerzonen je nach Tag:<\/p>\n<p>Juni bis September<\/p>\n<p>Montag, Mittwoch, Freitag und Samstag: Ses Illetes &amp; Cala Saona<br \/>\nDienstag, Donnerstag und Sonntag: Ses Illetes &amp; S\u2019Espalmador<\/p>\n<p>Wichtig: Aus Sicherheits- oder Wettergr\u00fcnden kann der Kapit\u00e4n die Ankerpunkte ohne vorherige Ank\u00fcndigung \u00e4ndern. Diese Entscheidungen werden getroffen, um die Sicherheit und das Wohlergehen der Passagiere zu gew\u00e4hrleisten und berechtigen nicht zu Entsch\u00e4digungen oder R\u00fcckerstattungen. <\/p>\n<h4><span style=\"text-decoration: underline;\">Line-up:<\/span><\/h4>\n<p>Musik an Bord<\/p>\n<p><strong>Kaufe deine Tickets im Vorverkauf f\u00fcr Formentera Wonders und spare Geld, bevor du nach Ibiza f\u00e4hrst.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Musik an Bord<\/p>\n","protected":false},"template":"","wcs-type":[308,2487,2907],"dj":[],"class_list":["post-1077261","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-boat-party","wcs-type-formentera-wonders","wcs-type-2907","wcs-room-playa-den-bossa-boat-parties"],"acf":[],"_wcs_timestamp":"1756889100","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class\/1077261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media\/609403"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media?parent=1077261"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/wcs-type?post=1077261"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/dj?post=1077261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}