{"id":1075566,"date":"2025-09-03T00:00:00","date_gmt":"2025-09-02T23:00:00","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/ibiza-boat-club-formentera-with-benefits-playa-den-bossa-boat-parties-2025-09-03\/"},"modified":"2025-09-03T00:00:00","modified_gmt":"2025-09-02T23:00:00","slug":"ibiza-boat-club-formentera-with-benefits-playa-den-bossa-boat-parties-2025-09-03","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/de\/event\/ibiza-boat-club-formentera-with-benefits-playa-den-bossa-boat-parties-2025-09-03\/","title":{"rendered":"Ibiza Boat Club Formentera mit Vorteilen"},"content":{"rendered":"<p>Das ist kein gew\u00f6hnlicher Ibiza-Bootsausflug. Tats\u00e4chlich ist es wichtig zu betonen: Formentera with Benefits ist \u00fcberhaupt keine Party, sondern ein ganzt\u00e4giges Luxus-Bootserlebnis, das du auf deiner Ibiza-Reise 2025 genie\u00dfen kannst.  <\/p>\n<p>Du wirst die wundersch\u00f6ne Insel Formentera in ihrer vollen Pracht erleben, zu Land und zu Wasser.<\/p>\n<p>Genie\u00dfe unbegrenzte Getr\u00e4nke an der Open Bar. Paella, bei der dir das Wasser im Mund zusammenl\u00e4uft. Badestopps und 5 Stunden Freizeit auf Formentera. Eine Sunset-Show-Cooking-Session. Dieses Erlebnis bietet alles und du wirst es im VIP-Stil mit eigenen Betten und Liegen an Bord genie\u00dfen.    <\/p>\n<h4><span style=\"text-decoration: underline;\">Line-up:<\/span><\/h4>\n<p>Musik an Bord<\/p>\n<p><strong>Kaufe deine Tickets im Vorverkauf f\u00fcr Ibiza Boat Club Formentera mit Vorteilen und spare Geld, bevor du nach Ibiza f\u00e4hrst.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Musik an Bord<\/p>\n","protected":false},"template":"","wcs-type":[308,422,2907],"dj":[],"class_list":["post-1075566","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-boat-party","wcs-type-ibiza-boat-club-formentera-with-benefits","wcs-type-2907","wcs-room-playa-den-bossa-boat-parties"],"acf":[],"_wcs_timestamp":"1756895400","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class\/1075566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media\/498039"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media?parent=1075566"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/wcs-type?post=1075566"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/dj?post=1075566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}