{"id":1066090,"date":"2026-01-20T16:14:19","date_gmt":"2026-01-20T16:14:19","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/john-summit-presents-experts-only-unvrs-2026-07-13\/"},"modified":"2026-04-16T20:34:40","modified_gmt":"2026-04-16T19:34:40","slug":"john-summit-presents-experts-only-unvrs-2026-07-13","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/de\/event\/john-summit-presents-experts-only-unvrs-2026-07-13\/","title":{"rendered":"John Summit pr\u00e4sentiert Experts Only"},"content":{"rendered":"<p>In einem fulminanten Ibiza-Deb\u00fct bringt John Summit seine Marke Experts Only jeden Montag f\u00fcr 9 explosive N\u00e4chte vom 1. Juni bis zum 27. Juli ins [UNVRS].<\/p>\n<p>Nachdem er globale Festivals als Headliner anf\u00fchrte und Arenen ausverkaufte, landet der aus Chicago stammende Star nun mit seiner allerersten Residency auf der Insel. Erwarte euphorische H\u00f6hen, tiefe emotionale Drops und diese unverkennbare Summit-Energie, w\u00e4hrend er die volle Kontrolle \u00fcber den [UNVRS] Main Room \u00fcbernimmt.<\/p>\n<p>Vom Meister pers\u00f6nlich kuratiert, wird das Line-up aufstrebende Stars und Top-Acts vom Experts Only Label in den Mittelpunkt stellen. Das ist nicht nur eine Party \u2013 das ist eine Bewegung. Eine der Must-see-Residencies des Sommers 2026.<\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/john-summit\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/john-summit-150x150.jpg\" alt=\"John Summit\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">John Summit<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/eli-brown\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Eli Brown\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Eli Brown<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/colyn\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Colyn\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Colyn<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/dreya-v\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Dreya V\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Dreya V<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/bender\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Bender\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Bender<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Main Room<br \/>\nJohn Summit<br \/>\nEli Brown<br \/>\nColyn<br \/>\nDreya V<\/p>\n<p>Wild Comet<br \/>\nBender<\/p>\n","protected":false},"template":"","wcs-type":[307,3810,3958,4458],"dj":[11892,11893,4461,8137,11818],"class_list":["post-1066090","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-superclub","wcs-type-monday","wcs-type-3958","wcs-type-john-summit-presents-experts-only","wcs-room-unvrs","dj-eli-brown","dj-dreya-v","dj-john-summit","dj-colyn","dj-bender"],"acf":[],"_wcs_timestamp":"1783983540","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class\/1066090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media\/1066240"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media?parent=1066090"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/wcs-type?post=1066090"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/dj?post=1066090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}