{"id":1007181,"date":"2025-11-25T14:26:32","date_gmt":"2025-11-25T14:26:32","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/soul-heaven-o-beach-2026-08-01\/"},"modified":"2026-03-25T18:04:29","modified_gmt":"2026-03-25T18:04:29","slug":"soul-heaven-o-beach-2026-08-01","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/de\/event\/soul-heaven-o-beach-2026-08-01\/","title":{"rendered":"Soul Heaven"},"content":{"rendered":"<p>Seit 2013 setzt Soul Heaven den Standard f\u00fcr Samstage im O Beach Ibiza \u2013 eine Poolparty, die f\u00fcr anspruchsvolle House-Musikliebhaber geschaffen wurde, die f\u00fcr Sonne, Rhythmus und Verbundenheit leben. <\/p>\n<p>Jahr f\u00fcr Jahr liefert es weiterhin den ultimativen Vocal-, Soulful-, Funky-Disco- und Deep-House-Soundtrack.<\/p>\n<p>Die w\u00f6chentliche Residenz von Soul Heaven hat schon immer ihre soul-infundierten und disco-inspirierten Wurzeln gefeiert, eine treue Anh\u00e4ngerschaft aufgebaut und einige der angesehensten K\u00fcnstler der Welt begr\u00fc\u00dft, darunter Sandy Rivera (Kings of Tomorrow), Grant Nelson, Jamie 3:26, Kenny Dope, Mousse T, Purple Disco Machine, Dave Lee und Norman Jay, neben aufstrebenden Talenten wie Monki, Katie Goodman und Superlover.<\/p>\n<p>Erwarte energiegeladene Auftritte, einen hervorragenden House-Soundtrack und die unverwechselbare O Beach Ibiza Atmosph\u00e4re, die Soul Heaven zu einem der gefragtesten Tageserlebnisse der Insel macht.<\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/jamie-love\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/jamie-love-150x150.jpg\" alt=\"Jamie Love\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Jamie Love<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/lucy-jane\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Lucy Jane\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Lucy Jane<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Headliner: TBA<br \/>\nJamie Love<br \/>\nLucy Jane<\/p>\n","protected":false},"template":"","wcs-type":[3815,3958,195,196],"dj":[4504,4519],"class_list":["post-1007181","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-saturday","wcs-type-3958","wcs-type-pool-party","wcs-type-soul-heaven","wcs-room-o-beach","dj-jamie-love","dj-lucy-jane"],"acf":[],"_wcs_timestamp":"1785589200","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class\/1007181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media\/993467"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media?parent=1007181"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/wcs-type?post=1007181"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/dj?post=1007181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}