{"id":1006741,"date":"2025-11-25T14:25:34","date_gmt":"2025-11-25T14:25:34","guid":{"rendered":"https:\/\/ticketsibiza.com\/event\/pool-party-o-beach-2026-09-25\/"},"modified":"2026-03-25T17:59:51","modified_gmt":"2026-03-25T17:59:51","slug":"pool-party-o-beach-2026-09-25","status":"publish","type":"class","link":"https:\/\/ticketsibiza.com\/de\/event\/pool-party-o-beach-2026-09-25\/","title":{"rendered":"Pool Party"},"content":{"rendered":"<p>Freitag wird die Freiheit gefeiert. <\/p>\n<p>Freaks, Uniques und Freigeister \u00fcbernehmen den Pool f\u00fcr die k\u00fchnste Party des O Beach. Mit erhebendem House, Live-Performern und einem vollen Spektrum an Farben und Kreativit\u00e4t ist die Pool Party der Ort, an dem die Selbstdarstellung regiert.  <\/p>\n<p>Komm, wie du bist. Alle Vibes sind willkommen. O Beach feiert nicht nur. Sie SPIELEN ALLE \u2013 DEN GANZEN TAG.   <\/p>\n<div class=\"wcs-lineup\"><h3 class=\"wcs-lineup__title\">Line-up<\/h3><ul class=\"wcs-lineup__list\"><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/dj-cameo\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/cameo-150x150.jpg\" alt=\"DJ Cameo\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">DJ Cameo<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/jamie-love\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/jamie-love-150x150.jpg\" alt=\"Jamie Love\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Jamie Love<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/lucy-jane\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Lucy Jane\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Lucy Jane<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/parris-taylor\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Parris Taylor\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Parris Taylor<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/sam-dungate\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/sun-dungate-150x150.jpg\" alt=\"Sam Dungate\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Sam Dungate<\/span><\/a><\/li><li class=\"wcs-lineup__item\"><a href=\"https:\/\/ticketsibiza.com\/de\/dj\/albert-bace-live-percussion\/\" class=\"wcs-lineup__link\"><img decoding=\"async\" src=\"https:\/\/ticketsibiza.com\/wp-content\/uploads\/2024\/09\/dj-pholder-150x150.jpg\" alt=\"Albert Bace (Live-Percussion)\" class=\"wcs-lineup__thumb\" title=\"\"><span class=\"wcs-lineup__name\">Albert Bace (Live-Percussion)<\/span><\/a><\/li><\/ul><\/div>\n","protected":false},"excerpt":{"rendered":"<p>DJ Cameo<br \/>\nJamie Love<br \/>\nLucy Jane<br \/>\nParris Taylor<br \/>\nSam Dungate<br \/>\nAlbert Bace (Live-Percussion)<\/p>\n","protected":false},"template":"","wcs-type":[195,3814,3958],"dj":[4607,4608,4504,4519,4556,4606],"class_list":["post-1006741","class","type-class","status-publish","has-post-thumbnail","hentry","wcs-type-pool-party","wcs-type-friday","wcs-type-3958","wcs-room-o-beach","dj-dj-cameo","dj-albert-bace-live-percussion","dj-jamie-love","dj-lucy-jane","dj-parris-taylor","dj-sam-dungate"],"acf":[],"_wcs_timestamp":"1790341200","_links":{"self":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class\/1006741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/class"}],"about":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/types\/class"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media\/993467"}],"wp:attachment":[{"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/media?parent=1006741"}],"wp:term":[{"taxonomy":"wcs-type","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/wcs-type?post=1006741"},{"taxonomy":"dj","embeddable":true,"href":"https:\/\/ticketsibiza.com\/de\/wp-json\/wp\/v2\/dj?post=1006741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}